{"id":2052,"date":"2025-07-24T08:24:03","date_gmt":"2025-07-24T08:24:03","guid":{"rendered":"https:\/\/globalmenta.com\/proyecto\/lonja-de-la-seda\/"},"modified":"2026-02-27T12:23:16","modified_gmt":"2026-02-27T12:23:16","slug":"lonja-della-seta","status":"publish","type":"proyecto","link":"https:\/\/globalmenta.com\/it\/proyecto\/lonja-della-seta\/","title":{"rendered":"Lonja della Seta di Valencia"},"content":{"rendered":"\n\t<section class=\"section custom-proyect-header\" id=\"section_527337852\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"slider-wrapper relative proyects-home-slider\" id=\"slider-549472250\" >\n    <div class=\"slider slider-type-fade slider-nav-dots-dashes slider-nav-circle slider-nav-large slider-nav-light slider-style-normal slider-show-nav\"\n        data-flickity-options='{\n            \"cellAlign\": \"center\",\n            \"imagesLoaded\": true,\n            \"lazyLoad\": 1,\n            \"freeScroll\": false,\n            \"wrapAround\": true,\n            \"autoPlay\": 5000,\n            \"pauseAutoPlayOnHover\" : false,\n            \"prevNextButtons\": false,\n            \"contain\" : true,\n            \"adaptiveHeight\" : true,\n            \"dragThreshold\" : 10,\n            \"percentPosition\": true,\n            \"pageDots\": true,\n            \"rightToLeft\": false,\n            \"draggable\": false,\n            \"selectedAttraction\": 0.1,\n            \"parallax\" : 0,\n            \"friction\": 0.6        }'\n        >\n        \n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1743500173\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:100vh;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"576\" src=\"https:\/\/globalmenta.com\/wp-content\/uploads\/2025\/07\/lonja-de-la-seda-4.jpg\" class=\"attachment-large size-large\" alt=\"lonja de la seda\" srcset=\"https:\/\/globalmenta.com\/wp-content\/uploads\/2025\/07\/lonja-de-la-seda-4.jpg 1920w, https:\/\/globalmenta.com\/wp-content\/uploads\/2025\/07\/lonja-de-la-seda-4-1024x579.jpg 1024w, https:\/\/globalmenta.com\/wp-content\/uploads\/2025\/07\/lonja-de-la-seda-4-768x434.jpg 768w, https:\/\/globalmenta.com\/wp-content\/uploads\/2025\/07\/lonja-de-la-seda-4-1536x868.jpg 1536w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1743500173 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n\t<\/div>\n\n\n<div class=\"row custom-proyect-title-row\"  id=\"row-1622390233\">\n\n\t<div id=\"col-548227646\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-4020530960\" class=\"text doubled-font txt-m-0\">\n\t\t\n<h1 data-animate=\"fadeIn\" data-animate-delay=\"200\"> <em>Lonja<\/em> della seta di Valencia<\/h1>\n\t\t\n<style>\n#text-4020530960 {\n  font-size: 1.5rem;\n  line-height: 1.1;\n  text-align: center;\n  color: rgb(255, 255, 255);\n}\n#text-4020530960 > * {\n  color: rgb(255, 255, 255);\n}\n@media (min-width:550px) {\n  #text-4020530960 {\n    font-size: 2.25rem;\n  }\n}\n@media (min-width:850px) {\n  #text-4020530960 {\n    font-size: 2.1875rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_527337852 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n  min-height: 100.01vh;\n  background-color: rgb(0, 0, 0);\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1749916719\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\t<div id=\"gap-1863627093\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1863627093 {\n  padding-top: 80px;\n}\n@media (min-width:550px) {\n  #gap-1863627093 {\n    padding-top: 160px;\n  }\n}\n@media (min-width:850px) {\n  #gap-1863627093 {\n    padding-top: 200px;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row\"  id=\"row-810867685\">\n\n\t<div id=\"col-2131848276\" class=\"col medium-12 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-2797164377\" class=\"text titles-font txt-m-0 fw-400\">\n\t\t\n<h1 data-animate=\"fadeIn\" data-animate-delay=\"200\"> <em>Lonja<\/em> della seta di Valencia<\/h1>\n\t\t\n<style>\n#text-2797164377 {\n  font-size: 2.25rem;\n  line-height: 1.2;\n}\n@media (min-width:550px) {\n  #text-2797164377 {\n    font-size: 3rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-672429472\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-672429472 {\n  padding-top: 15px;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-1218376666\" class=\"text proyecto-tags\">\n\t\t\n<ul>\n<li>Valencia, Spagna<\/li>\n<li>2021 &#8211; Presente<\/li>\n<li>Mediazione culturale, servizio di audioguide in 11 lingue<\/li>\n<\/ul>\n\t\t\n<style>\n#text-1218376666 {\n  font-size: 0.8rem;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-665260618\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-665260618 {\n  padding-top: 50px;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-2426902353\" class=\"text balance fw-700\">\n\t\t\n<p>Costruita alla fine del XV secolo in una delle zone pi\u00f9 vivaci e animate della citt\u00e0, era un moderno palazzo per il commercio. Attualmente \u00e8 un monumento visitabile, dichiarato Patrimonio dell&#8217;Umanit\u00e0 dall&#8217;UNESCO nel 1996.<\/p>\n\t\t\n<style>\n#text-2426902353 {\n  font-size: 1.25rem;\n  line-height: 1.5;\n}\n@media (min-width:550px) {\n  #text-2426902353 {\n    font-size: 1.375rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-2131848276 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:850px) {\n  #col-2131848276 > .col-inner {\n    padding: 0px 5% 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-2024682934\" class=\"col medium-12 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-526594408\" class=\"text fw-300\">\n\t\t\n<p><strong>Visita con audioguida in 11 lingue, un monumento imperdibile.<\/strong><\/p>\n<p>La Lonja di Valencia, conosciuta anche come Lonja dei Mercanti o Lonja della Seta, \u00e8 uno dei monumenti imprescindibili di Valencia. \u00c8 un grande edificio che si erge nella Plaza del Mercado, accanto a edifici emblematici come il Mercato Centrale e la chiesa dei Santos Juanes.<\/p>\n<p>La citt\u00e0 decise di costruire un luogo per accogliere il commercio, che era diventato l&#8217;attivit\u00e0 economica principale. Come conseguenza e dimostrazione della vivacit\u00e0 di Valencia, fu costruito un moderno tempio del commercio, una nuova lonja per i mercanti provenienti da diverse parti del mondo.<\/p>\n<p>Global Menta offre, dal 2021, il servizio di noleggio audioguide della Lonja per visitare il monumento nella sua interezza. Dal 2024, gestiamo anche le visite guidate alla Torre della Lonja.<\/p>\n<p><em>Offriamo diversi servizi in questo monumento dichiarato Patrimonio dell&#8217;Umanit\u00e0 dall&#8217;UNESCO dal 1996.<\/em><\/p>\n\t\t\n<style>\n#text-526594408 {\n  font-size: 1rem;\n  line-height: 1.4;\n}\n@media (min-width:550px) {\n  #text-526594408 {\n    font-size: 1.375rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-2024682934 > .col-inner {\n  padding: 0px 0px 0px 0%;\n}\n@media (min-width:850px) {\n  #col-2024682934 > .col-inner {\n    padding: 0px 0px 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t<div id=\"gap-63519036\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-63519036 {\n  padding-top: 50px;\n}\n@media (min-width:550px) {\n  #gap-63519036 {\n    padding-top: 70px;\n  }\n}\n@media (min-width:850px) {\n  #gap-63519036 {\n    padding-top: 100px;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1749916719 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1982325368\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-1980560248\">\n\n\t<div id=\"col-1714807590\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"row\"  id=\"row-1915365210\">\n\n\t<div id=\"col-1236384096\" class=\"col medium-6 small-12 large-6\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_175195575\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"786\" height=\"781\" src=\"https:\/\/globalmenta.com\/wp-content\/uploads\/2025\/07\/lonja-de-la-seda.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/globalmenta.com\/wp-content\/uploads\/2025\/07\/lonja-de-la-seda.jpg 786w, https:\/\/globalmenta.com\/wp-content\/uploads\/2025\/07\/lonja-de-la-seda-768x763.jpg 768w\" sizes=\"auto, (max-width: 786px) 100vw, 786px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_175195575 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1276486735\" class=\"col medium-6 small-12 large-6\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1444336018\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"788\" height=\"781\" src=\"https:\/\/globalmenta.com\/wp-content\/uploads\/2025\/07\/lonja-de-la-seda-1.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/globalmenta.com\/wp-content\/uploads\/2025\/07\/lonja-de-la-seda-1.jpg 788w, https:\/\/globalmenta.com\/wp-content\/uploads\/2025\/07\/lonja-de-la-seda-1-768x761.jpg 768w\" sizes=\"auto, (max-width: 788px) 100vw, 788px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1444336018 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1982325368 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_367548154\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\t<div id=\"gap-253999485\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-253999485 {\n  padding-top: 40px;\n}\n@media (min-width:850px) {\n  #gap-253999485 {\n    padding-top: 120px;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row\"  id=\"row-2133775008\">\n\n\t<div id=\"col-1913577522\" class=\"col transformacion-pasos-col medium-12 small-12 large-6 medium-col-first\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-1196547409\" class=\"text txt-m-0\">\n\t\t\n<h2>Come <em>trasformiamo<\/em><br \/>\nil museo in un punto di riferimento<br \/>\nculturale<\/h2>\n\t\t\n<style>\n#text-1196547409 {\n  font-size: 2rem;\n  line-height: 1.2;\n}\n@media (min-width:550px) {\n  #text-1196547409 {\n    font-size: 3rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-662703552\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-662703552 {\n  padding-top: 70px;\n}\n@media (min-width:550px) {\n  #gap-662703552 {\n    padding-top: 100px;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row row-collapse\"  id=\"row-1725577539\">\n\n\t<div id=\"col-329470370\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-2382939393\" class=\"text txt-m-0 fw-700 base-font uppercase\">\n\t\t\n<h3>Audioguide Multilingue e Accessibili<\/h3>\n\t\t\n<style>\n#text-2382939393 {\n  font-size: 1.5rem;\n  line-height: 1.3;\n}\n@media (min-width:550px) {\n  #text-2382939393 {\n    font-size: 1.375rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-537123201\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-537123201 {\n  padding-top: 24px;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-1296725725\" class=\"text fw-300\">\n\t\t\n<p>Offriamo un servizio completo di <strong>audioguide in 11 lingue<\/strong>:<br \/>Spagnolo, Valenciano, Inglese, Tedesco, Francese, Italiano, Portoghese, Olandese, Cinese, Giapponese e Russo. Questa diversit\u00e0 linguistica permette ai visitatori di godere di un percorso autonomo, arricchito e adattato alle loro esigenze culturali e linguistiche.<\/p>\n<p>Inoltre, le audioguide sono disponibili per <strong>ascolto diretto sul dispositivo<\/strong> o per <strong>download sullo smartphone del visitatore<\/strong>, offrendo cos\u00ec un&#8217;esperienza personalizzata e confortevole durante la visita.<\/p>\n<p>Nel nostro impegno per la <strong>accessibilit\u00e0 universale<\/strong>, disponiamo anche di <strong>videoguide in Lingua dei Segni Spagnola (LSE)<\/strong>, che consentono alle persone con disabilit\u00e0 uditive di godere appieno della visita e di scoprire la storia, il simbolismo e l&#8217;architettura della Lonja di Valencia.<\/p>\n\t\t\n<style>\n#text-1296725725 {\n  font-size: 1rem;\n  line-height: 1.4;\n}\n@media (min-width:550px) {\n  #text-1296725725 {\n    font-size: 1.375rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-569911722\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-569911722 {\n  padding-top: 40px;\n}\n@media (min-width:550px) {\n  #gap-569911722 {\n    padding-top: 60px;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row row-collapse\"  id=\"row-2116383644\">\n\n\t<div id=\"col-40058045\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-4167263697\" class=\"text txt-m-0 fw-700 base-font uppercase\">\n\t\t\n<h3>Sceneggiatura dei Contenuti Culturali<\/h3>\n\t\t\n<style>\n#text-4167263697 {\n  font-size: 1.5rem;\n  line-height: 1.3;\n}\n@media (min-width:550px) {\n  #text-4167263697 {\n    font-size: 1.375rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-487417116\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-487417116 {\n  padding-top: 24px;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-3072732726\" class=\"text txt-m-0 fw-300\">\n\t\t\n<p>Elaboriamo i contenuti delle audioguide a partire da un&#8217;attenta ricerca storica, adattandoli a un linguaggio chiaro, inclusivo e divulgativo. <strong>La sceneggiatura \u00e8 progettata da esperti di patrimonio e comunicazione culturale,<\/strong> con l&#8217;obiettivo di offrire una narrazione coerente, rigorosa e accattivante per pubblici diversi.<\/p>\n\t\t\n<style>\n#text-3072732726 {\n  font-size: 1rem;\n  line-height: 1.4;\n}\n@media (min-width:550px) {\n  #text-3072732726 {\n    font-size: 1.375rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-2021109648\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-2021109648 {\n  padding-top: 40px;\n}\n@media (min-width:550px) {\n  #gap-2021109648 {\n    padding-top: 60px;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<style>\n#row-2116383644 > .col > .col-inner {\n  padding: 30px 0px 0px 0px;\n}\n<\/style>\n<\/div>\n<div class=\"row row-collapse\"  id=\"row-1953321222\">\n\n\t<div id=\"col-1500485690\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-1501887113\" class=\"text txt-m-0 fw-700 base-font uppercase\">\n\t\t\n<h3>Visite Guidate Esclusive<\/h3>\n\t\t\n<style>\n#text-1501887113 {\n  font-size: 1.5rem;\n  line-height: 1.3;\n}\n@media (min-width:550px) {\n  #text-1501887113 {\n    font-size: 1.375rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-658116860\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-658116860 {\n  padding-top: 24px;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-1421325803\" class=\"text txt-m-0 fw-300\">\n\t\t\n<p>Dal 2023 siamo responsabili delle visite guidate alla Torre della Lonja, uno degli elementi architettonici pi\u00f9 singolari del complesso monumentale. Come azienda specializzata in mediazione culturale, abbiamo sviluppato e messo in atto un <strong>programma di 16 visite settimanali in tre lingue, oltre al sistema di prenotazioni associato al servizio.<\/strong> Questa esperienza, prevista per i prossimi due anni, offre ai visitatori la possibilit\u00e0 di scoprire spazi normalmente chiusi al pubblico, accompagnati da <strong>personale specializzato sul monumento<\/strong> e nell&#8217;interpretazione del patrimonio.<\/p>\n\t\t\n<style>\n#text-1421325803 {\n  font-size: 1rem;\n  line-height: 1.4;\n}\n@media (min-width:550px) {\n  #text-1421325803 {\n    font-size: 1.375rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-298333971\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-298333971 {\n  padding-top: 40px;\n}\n@media (min-width:550px) {\n  #gap-298333971 {\n    padding-top: 60px;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"\/it\/contatto\/\" class=\"button secondary is-outline\"  >\n\t\t<span>m\u00e1s informaci\u00f3n<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<style>\n#row-1953321222 > .col > .col-inner {\n  padding: 30px 0px 0px 0px;\n}\n<\/style>\n<\/div>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1913577522 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1913577522 > .col-inner {\n    padding: 0px 0px 0px 0px;\n  }\n}\n@media (min-width:850px) {\n  #col-1913577522 > .col-inner {\n    padding: 0px 0px 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1852159055\" class=\"col medium-12 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_203605513\">\n\t\t\t\t\t\t<div data-animate=\"fadeInRight\">\t\t<div class=\"img-inner dark\" style=\"margin:0px 0px 10px 0px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"788\" height=\"580\" src=\"https:\/\/globalmenta.com\/wp-content\/uploads\/2025\/07\/lonja-de-la-seda-2.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/globalmenta.com\/wp-content\/uploads\/2025\/07\/lonja-de-la-seda-2.jpg 788w, https:\/\/globalmenta.com\/wp-content\/uploads\/2025\/07\/lonja-de-la-seda-2-768x565.jpg 768w\" sizes=\"auto, (max-width: 788px) 100vw, 788px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/div>\t\t\t\t\t\t\n<style>\n#image_203605513 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_2096117192\">\n\t\t\t\t\t\t<div data-animate=\"fadeInRight\">\t\t<div class=\"img-inner dark\" style=\"margin:0px 0px 10px 0px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"788\" height=\"580\" src=\"https:\/\/globalmenta.com\/wp-content\/uploads\/2025\/07\/lonja-de-la-seda-3.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/globalmenta.com\/wp-content\/uploads\/2025\/07\/lonja-de-la-seda-3.jpg 788w, https:\/\/globalmenta.com\/wp-content\/uploads\/2025\/07\/lonja-de-la-seda-3-768x565.jpg 768w\" sizes=\"auto, (max-width: 788px) 100vw, 788px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/div>\t\t\t\t\t\t\n<style>\n#image_2096117192 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_932395438\">\n\t\t\t\t\t\t<div data-animate=\"fadeInRight\">\t\t<div class=\"img-inner dark\" style=\"margin:0px 0px 10px 0px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"788\" height=\"580\" src=\"https:\/\/globalmenta.com\/wp-content\/uploads\/2025\/07\/lonja-de-la-seda-6.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/globalmenta.com\/wp-content\/uploads\/2025\/07\/lonja-de-la-seda-6.jpg 788w, https:\/\/globalmenta.com\/wp-content\/uploads\/2025\/07\/lonja-de-la-seda-6-768x565.jpg 768w\" sizes=\"auto, (max-width: 788px) 100vw, 788px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/div>\t\t\t\t\t\t\n<style>\n#image_932395438 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1852159055 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:850px) {\n  #col-1852159055 > .col-inner {\n    padding: 0px 0px 0px 10%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t<div id=\"gap-1904122321\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1904122321 {\n  padding-top: 50px;\n}\n@media (min-width:550px) {\n  #gap-1904122321 {\n    padding-top: 100px;\n  }\n}\n@media (min-width:850px) {\n  #gap-1904122321 {\n    padding-top: 140px;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\n\t\t\n<style>\n#section_367548154 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":2054,"menu_order":13,"template":"","etiqueta-proyecto":[],"class_list":["post-2052","proyecto","type-proyecto","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Proyecto Lonja De La Seda | Global Menta<\/title>\n<meta name=\"description\" content=\"Proyecto de mediaci\u00f3n cultural en la Lonja de la Seda, con servicio de audiogu\u00edas en 11 idiomas, visitas guiadas y contenidos accesibles en este monumento.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/globalmenta.com\/it\/proyecto\/lonja-della-seta\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Proyecto Lonja De La Seda | Global Menta\" \/>\n<meta property=\"og:description\" content=\"Proyecto de mediaci\u00f3n cultural en la Lonja de la Seda, con servicio de audiogu\u00edas en 11 idiomas, visitas guiadas y contenidos accesibles en este monumento.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/globalmenta.com\/it\/proyecto\/lonja-della-seta\/\" \/>\n<meta property=\"og:site_name\" content=\"Global Menta\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mentacultural\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-27T12:23:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/globalmenta.com\/wp-content\/uploads\/2025\/07\/lonja-de-la-seda-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1085\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@globalmentaa\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/globalmenta.com\\\/it\\\/proyecto\\\/lonja-della-seta\\\/\",\"url\":\"https:\\\/\\\/globalmenta.com\\\/it\\\/proyecto\\\/lonja-della-seta\\\/\",\"name\":\"Proyecto Lonja De La Seda | Global Menta\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/globalmenta.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/globalmenta.com\\\/it\\\/proyecto\\\/lonja-della-seta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/globalmenta.com\\\/it\\\/proyecto\\\/lonja-della-seta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/globalmenta.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/lonja-de-la-seda-4.jpg\",\"datePublished\":\"2025-07-24T08:24:03+00:00\",\"dateModified\":\"2026-02-27T12:23:16+00:00\",\"description\":\"Proyecto de mediaci\u00f3n cultural en la Lonja de la Seda, con servicio de audiogu\u00edas en 11 idiomas, visitas guiadas y contenidos accesibles en este monumento.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/globalmenta.com\\\/it\\\/proyecto\\\/lonja-della-seta\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/globalmenta.com\\\/it\\\/proyecto\\\/lonja-della-seta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/globalmenta.com\\\/it\\\/proyecto\\\/lonja-della-seta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/globalmenta.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/lonja-de-la-seda-4.jpg\",\"contentUrl\":\"https:\\\/\\\/globalmenta.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/lonja-de-la-seda-4.jpg\",\"width\":1920,\"height\":1085,\"caption\":\"lonja de la seda\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/globalmenta.com\\\/it\\\/proyecto\\\/lonja-della-seta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/globalmenta.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lonja della Seta di Valencia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/globalmenta.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/globalmenta.com\\\/it\\\/\",\"name\":\"Global Menta\",\"description\":\"Gesti\u00f3n de Espacios Culturales\",\"publisher\":{\"@id\":\"https:\\\/\\\/globalmenta.com\\\/it\\\/#organization\"},\"alternateName\":\"Global Menta\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/globalmenta.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/globalmenta.com\\\/it\\\/#organization\",\"name\":\"Global Menta\",\"alternateName\":\"Global Menta\",\"url\":\"https:\\\/\\\/globalmenta.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/globalmenta.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/globalmenta.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/global-menta-logo.svg\",\"contentUrl\":\"https:\\\/\\\/globalmenta.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/global-menta-logo.svg\",\"width\":1,\"height\":1,\"caption\":\"Global Menta\"},\"image\":{\"@id\":\"https:\\\/\\\/globalmenta.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mentacultural\",\"https:\\\/\\\/x.com\\\/globalmentaa\",\"https:\\\/\\\/www.instagram.com\\\/globalmenta\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Proyecto Lonja De La Seda | Global Menta","description":"Proyecto de mediaci\u00f3n cultural en la Lonja de la Seda, con servicio de audiogu\u00edas en 11 idiomas, visitas guiadas y contenidos accesibles en este monumento.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/globalmenta.com\/it\/proyecto\/lonja-della-seta\/","og_locale":"it_IT","og_type":"article","og_title":"Proyecto Lonja De La Seda | Global Menta","og_description":"Proyecto de mediaci\u00f3n cultural en la Lonja de la Seda, con servicio de audiogu\u00edas en 11 idiomas, visitas guiadas y contenidos accesibles en este monumento.","og_url":"https:\/\/globalmenta.com\/it\/proyecto\/lonja-della-seta\/","og_site_name":"Global Menta","article_publisher":"https:\/\/www.facebook.com\/mentacultural","article_modified_time":"2026-02-27T12:23:16+00:00","og_image":[{"width":1920,"height":1085,"url":"https:\/\/globalmenta.com\/wp-content\/uploads\/2025\/07\/lonja-de-la-seda-4.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@globalmentaa","twitter_misc":{"Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/globalmenta.com\/it\/proyecto\/lonja-della-seta\/","url":"https:\/\/globalmenta.com\/it\/proyecto\/lonja-della-seta\/","name":"Proyecto Lonja De La Seda | Global Menta","isPartOf":{"@id":"https:\/\/globalmenta.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/globalmenta.com\/it\/proyecto\/lonja-della-seta\/#primaryimage"},"image":{"@id":"https:\/\/globalmenta.com\/it\/proyecto\/lonja-della-seta\/#primaryimage"},"thumbnailUrl":"https:\/\/globalmenta.com\/wp-content\/uploads\/2025\/07\/lonja-de-la-seda-4.jpg","datePublished":"2025-07-24T08:24:03+00:00","dateModified":"2026-02-27T12:23:16+00:00","description":"Proyecto de mediaci\u00f3n cultural en la Lonja de la Seda, con servicio de audiogu\u00edas en 11 idiomas, visitas guiadas y contenidos accesibles en este monumento.","breadcrumb":{"@id":"https:\/\/globalmenta.com\/it\/proyecto\/lonja-della-seta\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/globalmenta.com\/it\/proyecto\/lonja-della-seta\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/globalmenta.com\/it\/proyecto\/lonja-della-seta\/#primaryimage","url":"https:\/\/globalmenta.com\/wp-content\/uploads\/2025\/07\/lonja-de-la-seda-4.jpg","contentUrl":"https:\/\/globalmenta.com\/wp-content\/uploads\/2025\/07\/lonja-de-la-seda-4.jpg","width":1920,"height":1085,"caption":"lonja de la seda"},{"@type":"BreadcrumbList","@id":"https:\/\/globalmenta.com\/it\/proyecto\/lonja-della-seta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/globalmenta.com\/it\/"},{"@type":"ListItem","position":2,"name":"Lonja della Seta di Valencia"}]},{"@type":"WebSite","@id":"https:\/\/globalmenta.com\/it\/#website","url":"https:\/\/globalmenta.com\/it\/","name":"Global Menta","description":"Gesti\u00f3n de Espacios Culturales","publisher":{"@id":"https:\/\/globalmenta.com\/it\/#organization"},"alternateName":"Global Menta","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/globalmenta.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/globalmenta.com\/it\/#organization","name":"Global Menta","alternateName":"Global Menta","url":"https:\/\/globalmenta.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/globalmenta.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/globalmenta.com\/wp-content\/uploads\/2025\/05\/global-menta-logo.svg","contentUrl":"https:\/\/globalmenta.com\/wp-content\/uploads\/2025\/05\/global-menta-logo.svg","width":1,"height":1,"caption":"Global Menta"},"image":{"@id":"https:\/\/globalmenta.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mentacultural","https:\/\/x.com\/globalmentaa","https:\/\/www.instagram.com\/globalmenta\/"]}]}},"_links":{"self":[{"href":"https:\/\/globalmenta.com\/it\/wp-json\/wp\/v2\/proyecto\/2052","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/globalmenta.com\/it\/wp-json\/wp\/v2\/proyecto"}],"about":[{"href":"https:\/\/globalmenta.com\/it\/wp-json\/wp\/v2\/types\/proyecto"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalmenta.com\/it\/wp-json\/wp\/v2\/media\/2054"}],"wp:attachment":[{"href":"https:\/\/globalmenta.com\/it\/wp-json\/wp\/v2\/media?parent=2052"}],"wp:term":[{"taxonomy":"etiqueta-proyecto","embeddable":true,"href":"https:\/\/globalmenta.com\/it\/wp-json\/wp\/v2\/etiqueta-proyecto?post=2052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}